{"id":3377,"date":"2026-04-09T18:53:35","date_gmt":"2026-04-09T17:53:35","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/?p=3377"},"modified":"2026-05-20T18:56:52","modified_gmt":"2026-05-20T17:56:52","slug":"ajemates","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/ajemates\/","title":{"rendered":"AJEMATES"},"content":{"rendered":"<p>\u00bfQui\u00e9n dice que las matem\u00e1ticas tienen que ser aburridas? Esta semana, los alumnos de 3.\u00ba, 4.\u00ba, 5.\u00ba y 6.\u00ba de Primaria han cambiado por un d\u00eda los libros por pantallas y tableros gracias a &#8220;Ajemates&#8221;, una iniciativa genial de la Diputaci\u00f3n de M\u00e1laga.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3379\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/files\/2026\/05\/20260414_092543-1024x768.jpg\" alt=\"\" width=\"1024\" height=\"768\" srcset=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/files\/2026\/05\/20260414_092543-980x735.jpg 980w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/files\/2026\/05\/20260414_092543-480x360.jpg 480w\" sizes=\"(min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/p>\n<p>A trav\u00e9s de las pantallas de clase, fusionamos el ajedrez digital con retos matem\u00e1ticos. Los chicos y chicas se lo pasaron en grande aceptando los desaf\u00edos del maestro Cristian Claros, \u00a1que los tuvo a todos enganchad\u00edsimos!<\/p>\n<p>\ud83e\udde0 \u00bfPor qu\u00e9 nos encanta esta actividad?<br \/>\nM\u00e1s all\u00e1 de jugar, este taller es pura pedagog\u00eda \u00fatil. Sin darse cuenta, los alumnos estuvieron entrenando:<\/p>\n<ul>\n<li>C\u00e1lculo mental r\u00e1pido para resolver las jugadas.<\/li>\n<li>L\u00f3gica y estrategia antes de mover cada pieza.<\/li>\n<li>Paciencia y concentraci\u00f3n<\/li>\n<\/ul>\n<p>Queremos dar las gracias a la Diputaci\u00f3n de M\u00e1laga por traernos este proyecto que demuestra que se puede aprender much\u00edsimo pas\u00e1ndolo bien.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQui\u00e9n dice que las matem\u00e1ticas tienen que ser aburridas? Esta semana, los alumnos de 3.\u00ba, 4.\u00ba, 5.\u00ba y 6.\u00ba de Primaria han cambiado por un d\u00eda los libros por pantallas y tableros gracias a &#8220;Ajemates&#8221;, una iniciativa genial de la Diputaci\u00f3n de M\u00e1laga. A trav\u00e9s de las pantallas de clase, fusionamos el ajedrez digital con [&hellip;]<\/p>\n","protected":false},"author":11212,"featured_media":3378,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/posts\/3377"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/users\/11212"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/comments?post=3377"}],"version-history":[{"count":1,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/posts\/3377\/revisions"}],"predecessor-version":[{"id":3380,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/posts\/3377\/revisions\/3380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/media\/3378"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/media?parent=3377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/categories?post=3377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceip-maestro-jose-duran\/wp-json\/wp\/v2\/tags?post=3377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}