{"id":923,"date":"2020-04-23T13:28:54","date_gmt":"2020-04-23T11:28:54","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/?p=923"},"modified":"2020-04-23T13:28:54","modified_gmt":"2020-04-23T11:28:54","slug":"dia-del-libro-23-04-2020","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/dia-del-libro-23-04-2020\/","title":{"rendered":"D\u00cdA DEL LIBRO 23\/04\/2020"},"content":{"rendered":"<p>Aunque estemos en casa, no nos olvidamos de celebrar el d\u00eda del libro. Se han hecho actividades por cursos haciendo alusi\u00f3n a esta efem\u00e9ride. El AMPA nos propuso un reportaje de fotos en el cual nuestro alumnado mostrase los libros que lee en casa y eso hemos hecho y queremos compartir con todos. Muchas gracias.<\/p>\n<div style=\"width: 750px;\" class=\"wp-video\"><!--[if lt IE 9]><script>document.createElement('video');<\/script><![endif]-->\n<video class=\"wp-video-shortcode\" id=\"video-923-1\" width=\"750\" height=\"422\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-libro.-Primaria.mp4?_=1\" \/><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-libro.-Primaria.mp4\">https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-libro.-Primaria.mp4<\/a><\/video><\/div>\n<div style=\"width: 750px;\" class=\"wp-video\"><video class=\"wp-video-shortcode\" id=\"video-923-2\" width=\"750\" height=\"422\" preload=\"metadata\" controls=\"controls\"><source type=\"video\/mp4\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-Libro-Infantil.mp4?_=2\" \/><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-Libro-Infantil.mp4\">https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/files\/2020\/04\/D\u00eda-del-Libro-Infantil.mp4<\/a><\/video><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Aunque estemos en casa, no nos olvidamos de celebrar el d\u00eda del libro. Se han hecho actividades por cursos haciendo alusi\u00f3n a esta efem\u00e9ride. El AMPA nos propuso un reportaje de fotos en el cual nuestro alumnado mostrase los libros que lee en casa y eso hemos hecho y queremos compartir con todos. Muchas gracias.<\/p>\n","protected":false},"author":5935,"featured_media":926,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1739601],"tags":[1739602],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/posts\/923"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/users\/5935"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/comments?post=923"}],"version-history":[{"count":1,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/posts\/923\/revisions"}],"predecessor-version":[{"id":927,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/posts\/923\/revisions\/927"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/media\/926"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/media?parent=923"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/categories?post=923"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceiplanoria\/wp-json\/wp\/v2\/tags?post=923"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}