{"id":3960,"date":"2023-06-08T13:28:49","date_gmt":"2023-06-08T11:28:49","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/?p=3960"},"modified":"2023-06-08T13:30:32","modified_gmt":"2023-06-08T11:30:32","slug":"3960-2","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/3960-2\/","title":{"rendered":"Fiesta FIN DE CURSO 2022-2023"},"content":{"rendered":"<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">El CEIP Marismas de Hinojos se despide del curso con su tradicional fiesta familiar&nbsp;<\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">Este a\u00f1o ser\u00e1 el <strong>viernes16 de junio<\/strong>, en la Avenida Reyes Cat\u00f3licos, a partir de las <strong>20:00h&nbsp;<\/strong><\/span><\/p>\n<p><span class=\"css-901oao css-16my406 r-poiln3 r-bcqeeo r-qvutc0\">La diversi\u00f3n est\u00e1 asegurada con la dinamizaci\u00f3n de talleres y actuaciones musicales. <\/span><\/p>\n<p style=\"text-align: center\"><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/files\/2023\/06\/Fx8J-eyXwAAFdsa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-3961\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/files\/2023\/06\/Fx8J-eyXwAAFdsa-212x300.jpg\" alt=\"\" width=\"212\" height=\"300\" srcset=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/files\/2023\/06\/Fx8J-eyXwAAFdsa-212x300.jpg 212w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/files\/2023\/06\/Fx8J-eyXwAAFdsa.jpg 481w\" sizes=\"(max-width: 212px) 100vw, 212px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El CEIP Marismas de Hinojos se despide del curso con su tradicional fiesta familiar&nbsp; Este a\u00f1o ser\u00e1 el viernes16 de&#46;&#46;&#46;<\/p>\n","protected":false},"author":669,"featured_media":3961,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[526],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/posts\/3960"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/users\/669"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/comments?post=3960"}],"version-history":[{"count":4,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/posts\/3960\/revisions"}],"predecessor-version":[{"id":3965,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/posts\/3960\/revisions\/3965"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/media\/3961"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/media?parent=3960"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/categories?post=3960"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipmarismasdehinojos\/wp-json\/wp\/v2\/tags?post=3960"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}