{"id":15948,"date":"2025-07-02T11:53:56","date_gmt":"2025-07-02T10:53:56","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/?page_id=15948"},"modified":"2026-05-25T09:17:17","modified_gmt":"2026-05-25T08:17:17","slug":"impresos-servicios-complementarios","status":"publish","type":"page","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/impresos-servicios-complementarios\/","title":{"rendered":"Impresos Servicios Complementarios"},"content":{"rendered":"<div class=\" d-lg-block mb-lg-0 ml-lg-0 mr-lg-0 mt-lg-4 pb-lg-0 pl-lg-0 pr-lg-0 pt-lg-0 text-lg-left mt-4 mt-sm-4 mt-md-4\">\n<div id=\"fragment-502-pxal\">\n<div class=\"fragment_401 pt-4 banner-video\">\n<table style=\"border-collapse: collapse;width: 100%\">\n<tbody>\n<tr>\n<td style=\"width: 50%;text-align: center\">\n<div class=\"documento-entry__preview pdf\"><a title=\"Ver documento Anexo II: Solicitud de servicio de aula matinal, comedor escolar o actividades extraescolares\" href=\"https:\/\/drive.google.com\/open?id=1g8MeLbd3cd_ifvTxU11txPmONGiFJJRO&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" id=\"the-canvas-837345\" class=\"documento-entry__preview--canvas alignnone\" src=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/documents\/20123\/837342\/ANEXO%20II%20corregido.pdf\/d8acfa29-d283-43ee-81e0-f6aa57ecfe56?version=1.0&amp;documentThumbnail=1\" alt=\"\" width=\"212\" height=\"300\"><\/a><\/div>\n<div class=\"documento-entry__datos\">\n<h5 class=\"documento-entry__datos__title\"><a class=\"documento-entry__datos--titulo\" title=\"Ver documento Anexo II: Solicitud de servicio de aula matinal, comedor escolar o actividades extraescolares\" href=\"https:\/\/drive.google.com\/open?id=1g8MeLbd3cd_ifvTxU11txPmONGiFJJRO&amp;usp=drive_fs\" target=\"_blank\" rel=\"noopener\">Anexo II: Solicitud de servicio de aula matinal, comedor escolar o actividades extraescolares<\/a><\/h5>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/td>\n<td style=\"width: 50%;text-align: center\">\n<div class=\"documento-entry__preview pdf\"><a title=\"Ver documento Anexo V: Solicitud de gratuidad\/bonificaci\u00f3n del precio p\u00fablico por los servicios complementarios de aula matinal, comedor escolar y actividades extraescolares\" href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/documents\/20123\/837342\/02052024_ANEXO_V.pdf\/ae6d7cc2-28bf-2701-eca8-a72f3ccd517c?version=1.0\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" id=\"the-canvas-837381\" class=\"documento-entry__preview--canvas alignnone\" src=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/documents\/20123\/837342\/02052024_ANEXO_V.pdf\/ae6d7cc2-28bf-2701-eca8-a72f3ccd517c?version=1.0&amp;documentThumbnail=1\" alt=\"\" width=\"212\" height=\"300\"><\/a><\/div>\n<div class=\"documento-entry__datos\">\n<h5 class=\"documento-entry__datos__title\"><a class=\"documento-entry__datos--titulo\" title=\"Ver documento Anexo V: Solicitud de gratuidad\/bonificaci\u00f3n del precio p\u00fablico por los servicios complementarios de aula matinal, comedor escolar y actividades extraescolares\" href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portales\/documents\/20123\/837342\/02052024_ANEXO_V.pdf\/ae6d7cc2-28bf-2701-eca8-a72f3ccd517c?version=1.0\" target=\"_blank\" rel=\"noopener\">Anexo V: Solicitud de gratuidad\/bonificaci\u00f3n del precio p\u00fablico por los servicios complementarios de aula matinal, comedor escolar y actividades extraescolares<\/a><\/h5>\n<p><em><strong><a href=\"https:\/\/view.genial.ly\/630f2bbba52702001abbfc4c\/presentation-bonificaciones-vc-22-23\" target=\"_blank\" rel=\"noopener noreferrer\">Presentaci\u00f3n \u00bfC\u00f3mo solicitar la bonificaci\u00f3n?<\/a><\/strong><\/em><\/p>\n<\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n<div class=\" d-lg-block mb-lg-0 ml-lg-0 mr-lg-0 mt-lg-0 pb-lg-0 pl-lg-0 pr-lg-0 pt-lg-0 text-lg-left\">\n<div id=\"fragment-0-qhtg\">\n<div id=\"p_p_id_com_liferay_asset_publisher_web_portlet_AssetPublisherPortlet_INSTANCE_qhtg_\" class=\"portlet-boundary portlet-boundary_com_liferay_asset_publisher_web_portlet_AssetPublisherPortlet_ portlet-static portlet-static-end portlet-decorate portlet-asset-publisher \">\n<section id=\"portlet_com_liferay_asset_publisher_web_portlet_AssetPublisherPortlet_INSTANCE_qhtg\" class=\"portlet\">\n<div class=\"portlet-content\">\n<div class=\" portlet-content-container\">\n<div class=\"portlet-body\">\n<div class=\"documentos-entries\">\n<div class=\"documento-entry no-content-folder\">\n<div class=\"documento-entry__preview pdf\">\n<div class=\"documento-entry__preview--icon font-icomoon icon-ico-pdf\">\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify\"><span style=\"font-size: 12pt\"><strong>Otra documentaci\u00f3n a entregar. <\/strong><\/span><a href=\"https:\/\/drive.google.com\/file\/d\/1oMLTyCWtPhN5l68AIyUlqgV3uPUuOsv9\/view?usp=sharing\" target=\"_blank\" rel=\"noopener noreferrer\"><em>(Extracto de la normativa sobre criterios de admisi\u00f3n y acreditaci\u00f3n de la situaci\u00f3n laboral y familiar)<\/em><\/a><\/p>\n<p style=\"text-align: justify\"><strong><u>Importante:<\/u><\/strong>&nbsp;Si al solicitar el servicio de&nbsp;<u>Aula Matinal<\/u>&nbsp;y&nbsp;<u>Comedor<\/u>&nbsp;se necesita acreditar la&nbsp;<strong>vida laboral<\/strong>&nbsp;de los progenitores y los&nbsp;<strong>certificados de trabajo<\/strong>, estos deben ser v\u00e1lidos con&nbsp;<strong>fecha a partir del 1 de junio<\/strong>.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/section>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Anexo II: Solicitud de servicio de aula matinal, comedor escolar o actividades extraescolares &nbsp; &nbsp; Anexo V: Solicitud de gratuidad\/bonificaci\u00f3n del precio p\u00fablico por los servicios complementarios de aula matinal, comedor escolar y actividades extraescolares Presentaci\u00f3n \u00bfC\u00f3mo solicitar la bonificaci\u00f3n? &nbsp; Otra documentaci\u00f3n a entregar. (Extracto de la normativa sobre criterios de admisi\u00f3n y acreditaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":4543,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","ngg_post_thumbnail":0,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/pages\/15948"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/users\/4543"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/comments?post=15948"}],"version-history":[{"count":8,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/pages\/15948\/revisions"}],"predecessor-version":[{"id":16382,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/pages\/15948\/revisions\/16382"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipreinafabiola\/wp-json\/wp\/v2\/media?parent=15948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}