{"id":3030,"date":"2021-11-19T16:37:26","date_gmt":"2021-11-19T16:37:26","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/?p=3030"},"modified":"2021-11-19T16:37:26","modified_gmt":"2021-11-19T16:37:26","slug":"trabajamos-el-equilibrio","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/trabajamos-el-equilibrio\/","title":{"rendered":"Trabajamos el equilibrio"},"content":{"rendered":"<p>En estos d\u00edas hemos estado trabando el equilibrio desde el \u00e1rea de Educaci\u00f3n F\u00edsica.&nbsp;<\/p>\n<p>Como actividad final, el alumnado pudo traer sus bicis y patinetes para realizar un circuito organizado con la colaboraci\u00f3n de los compa\u00f1eros de 3er. Ciclo, que nos hicieron unas se\u00f1ales de tr\u00e1ficos muy chulas.<\/p>\nngg_shortcode_0_placeholder\n","protected":false},"excerpt":{"rendered":"<p>En estos d\u00edas hemos estado trabando el equilibrio desde el \u00e1rea de Educaci\u00f3n F\u00edsica.&nbsp; Como actividad final, el alumnado pudo traer sus bicis y patinetes para realizar un circuito organizado con la colaboraci\u00f3n de&#46;&#46;&#46;<\/p>\n","protected":false},"author":10716,"featured_media":3031,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[26636,307390],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/posts\/3030"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/users\/10716"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/comments?post=3030"}],"version-history":[{"count":2,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/posts\/3030\/revisions"}],"predecessor-version":[{"id":3071,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/posts\/3030\/revisions\/3071"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/media\/3031"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/media?parent=3030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/categories?post=3030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanginesdelajara\/wp-json\/wp\/v2\/tags?post=3030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}