{"id":2289,"date":"2020-10-04T08:33:20","date_gmt":"2020-10-04T08:33:20","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/?p=2289"},"modified":"2020-10-04T10:26:01","modified_gmt":"2020-10-04T10:26:01","slug":"iniciocurso","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/iniciocurso\/","title":{"rendered":"Inicio de curso 2020\/2021"},"content":{"rendered":"<h2><strong>Informaci\u00f3n sobre el inicio del curso 2020\/2021:<\/strong><\/h2>\n<p style=\"text-align: left\"><strong><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-2299 aligncenter\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed-300x232.jpg\" alt=\"\" width=\"221\" height=\"171\" srcset=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed-300x232.jpg 300w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed-24x19.jpg 24w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed-36x28.jpg 36w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed-48x37.jpg 48w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/unnamed.jpg 512w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/strong><\/p>\n<p style=\"text-align: left\">Estimadas familias:<\/p>\n<p style=\"text-align: justify\">Ante el inicio del nuevo curso escolar 2020\/2021, teniendo en cuenta la situaci\u00f3n sanitaria que llevamos viviendo desde hace varios meses, el comienzo de la actividad presencial en los centros educativos se llevar\u00e1 a caboa partir de una planificaci\u00f3n profunda y rigurosa, estableciendo medidas de prevenci\u00f3n e higiene as\u00ed como de especial protecci\u00f3n para minimizar al m\u00e1ximo el riesgo.<\/p>\n<p style=\"text-align: justify\">Teniendo en cuenta las diversas Instrucciones derivadas de la Consejer\u00eda de Educaci\u00f3n y Deporte de nuestra comunidad, nuestro colegio cuenta con una Comisi\u00f3n Espec\u00edfica que realizar\u00e1 un seguimiento de las actuaciones y medidas adoptadas, as\u00ed como con un Protocolo de Actuaci\u00f3n COVID-19 donde se recogen las medidas de tipo pedag\u00f3gico y organizativo del centro.<\/p>\n<p style=\"text-align: justify\">No obstante, la vuelta al colegio segura es responsabilidad de toda la comunidad educativa. Es por ello, que debemos colaborar y concienciarnos del cumplimiento de las normas establecidas.<\/p>\n<p style=\"text-align: justify\">Para m\u00e1s informaci\u00f3n, ver enlace:<\/p>\n<h4 style=\"text-align: center\"><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/files\/2020\/10\/inicio-curso-20-21.pdf\">Inicio curso 20-21<\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n sobre el inicio del curso 2020\/2021: Estimadas familias: Ante el inicio del nuevo curso escolar 2020\/2021, teniendo en cuenta la situaci\u00f3n sanitaria que llevamos viviendo desde hace varios meses, el comienzo de la&#46;&#46;&#46;<\/p>\n","protected":false},"author":10807,"featured_media":2299,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[526],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/posts\/2289"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/users\/10807"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/comments?post=2289"}],"version-history":[{"count":13,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/posts\/2289\/revisions"}],"predecessor-version":[{"id":2317,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/posts\/2289\/revisions\/2317"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/media\/2299"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/media?parent=2289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/categories?post=2289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipsanisicio\/wp-json\/wp\/v2\/tags?post=2289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}