{"id":1253,"date":"2011-07-06T18:03:02","date_gmt":"2011-07-06T18:03:02","guid":{"rendered":"http:\/\/ceipva.wordpress.com\/?p=1253"},"modified":"2011-07-06T18:03:02","modified_gmt":"2011-07-06T18:03:02","slug":"agradecimientos-a-inforae","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/agradecimientos-a-inforae\/","title":{"rendered":"AGRADECIMIENTOS A INFORAE"},"content":{"rendered":"<p>Estimadas familias:<\/p>\n<p>Desde el Centro queremos agradecer el trabajo realizado por la empresa que presta los servicios de Actividades extraescolares y el Depote en la Escuela . Adem\u00e1s de prestar sus servicios, su directora, M\u00aa Luz, siempre colabora en los distintos eventos que organiza el Centro.<\/p>\n<p>&nbsp;<\/p>\n<p>Gracias por todo.<\/p>\n<p>&nbsp;<\/p>\n<p>La Direcci\u00f3n<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estimadas familias: Desde el Centro queremos agradecer el trabajo realizado por la empresa que presta los servicios de Actividades extraescolares y el Depote en la Escuela . Adem\u00e1s de prestar sus servicios, su directora, M\u00aa Luz, siempre colabora en los distintos eventos que organiza el Centro. &nbsp; Gracias por todo. &nbsp; La Direcci\u00f3n<\/p>\n","protected":false},"author":15476,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/posts\/1253"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/users\/15476"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/comments?post=1253"}],"version-history":[{"count":0,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/posts\/1253\/revisions"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/media?parent=1253"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/categories?post=1253"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipva\/wp-json\/wp\/v2\/tags?post=1253"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}