{"id":6599,"date":"2024-10-03T20:11:36","date_gmt":"2024-10-03T20:11:36","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/?p=6599"},"modified":"2024-10-03T20:11:36","modified_gmt":"2024-10-03T20:11:36","slug":"publicacion-del-censo","status":"publish","type":"post","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/publicacion-del-censo\/","title":{"rendered":"PUBLICACI\u00d3N DEL CENSO"},"content":{"rendered":"<p><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/files\/2024\/10\/consejo_escolar_1.jpg\"><img decoding=\"async\" class=\"size-medium wp-image-6600 alignleft\" src=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/files\/2024\/10\/consejo_escolar_1-300x142.jpg\" alt=\"\" width=\"300\" height=\"142\" srcset=\"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/files\/2024\/10\/consejo_escolar_1-300x142.jpg 300w, https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/files\/2024\/10\/consejo_escolar_1.jpg 397w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>El pr\u00f3ximo mes de noviembre se realizar\u00e1n las elecciones para elegir representantes del Consejo Escolar. La <a href=\"https:\/\/www.juntadeandalucia.es\/educacion\/portals\/web\/inspeccion-educativa\/normativa-d\/-\/contenidos\/detalle\/resolucion-de-6-de-septiembre-de-2024-de-la-direccion-general-de-participacion-e-inclusion-educativa-por-la-que-se-133tikgfq27hy\"><strong>RESOLUCI\u00d3N de 6 de septiembre de 2024<\/strong><\/a>, de la Direcci\u00f3n General de Ordenaci\u00f3n, Inclusi\u00f3n, Participaci\u00f3n y Evaluaci\u00f3n Educativa, establece el calendario para el desarrollo de estas <strong>elecciones <\/strong>de los centros docentes sostenidos con fondos p\u00fablicos de la Comunidad Aut\u00f3noma de Andaluc\u00eda, a excepci\u00f3n de los centros espec\u00edficos de educaci\u00f3n permanente de personas adultas para el curso 2024\/2025.<\/p>\n<p>Ya est\u00e1 disponible en el <strong>tabl\u00f3n de anuncios del centro el censo provisional de padres y madres<\/strong> donde se podr\u00e1n consultar todos los datos para poder votar.<\/p>\n<p>Recordamos tambi\u00e9n que el <strong>pr\u00f3ximo lunes no habr\u00e1 colegio<\/strong> con motivo de las fiestas locales de la Virgen del Rosario.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo mes de noviembre se realizar\u00e1n las elecciones para elegir representantes del Consejo Escolar. La RESOLUCI\u00d3N de 6 de septiembre de 2024, de la Direcci\u00f3n General de Ordenaci\u00f3n, Inclusi\u00f3n, Participaci\u00f3n y Evaluaci\u00f3n Educativa, establece el calendario para el desarrollo de estas elecciones de los&#46;&#46;&#46;<\/p>\n","protected":false},"author":10667,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[26636],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/posts\/6599"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/users\/10667"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/comments?post=6599"}],"version-history":[{"count":1,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/posts\/6599\/revisions"}],"predecessor-version":[{"id":6601,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/posts\/6599\/revisions\/6601"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/media?parent=6599"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/categories?post=6599"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/ceipvr\/wp-json\/wp\/v2\/tags?post=6599"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}