{"id":8,"count":1,"description":"","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/cronistastv\/category\/clase-de-cocina\/","name":"Clase de cocina","slug":"clase-de-cocina","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/cronistastv\/wp-json\/wp\/v2\/categories\/8"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/cronistastv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/cronistastv\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/cronistastv\/wp-json\/wp\/v2\/posts?categories=8"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}