{"id":329,"date":"2019-07-07T08:43:40","date_gmt":"2019-07-07T08:43:40","guid":{"rendered":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/?page_id=329"},"modified":"2019-07-07T16:20:29","modified_gmt":"2019-07-07T16:20:29","slug":"puntada-a-puntada-costura","status":"publish","type":"page","link":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/_proyectos\/puntada-a-puntada-costura\/","title":{"rendered":"Puntada a puntada (Costura)"},"content":{"rendered":"<p style=\"text-align: center\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/salesianossantander.org\/wp-content\/uploads\/2019\/02\/IMG-20190222-WA0003.jpg?resize=960%2C500\" alt=\"Resultado de imagen de costura educacion infantil\"><\/p>\n<p>En esta ocasi\u00f3n, vamos a trabajar la&nbsp;<strong>UDI Puntada a puntada (Costura)<\/strong>. Esta unidad did\u00e1ctica va ayudara a nuestros alumnos y alumnas a aprender labores como coser o tejer, que tienen un gran valor pedag\u00f3gico desde la etapa de educaci\u00f3n infantil. Adem\u00e1s les mostrar\u00e1 el oficio de la costura como parte importante de nuestra fiesta local por excelencia: el Carnaval.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft\" src=\"http:\/\/www.aikidocordoba.com\/wordpress\/wp-content\/uploads\/2016\/01\/enlace.png\" alt=\"Resultado de imagen de click enlace\" width=\"70\" height=\"70\"><\/p>\n<p>&nbsp;<\/p>\n<p>Mira&nbsp;<strong><a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/category\/costura\/\">este enlace<\/a><\/strong>, donde puedes ver todas las entradas en el&nbsp;<a href=\"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/_noticiero\/\">Blog de La Maestra Mari Carmen<\/a>, relacionadas con esta Unidad Did\u00e1ctica. En estas entradas en el blog se pueden ver, entre otras cosas, v\u00eddeocuentos en los que se habla y se trabajan las emociones en los ni\u00f1os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En esta ocasi\u00f3n, vamos a trabajar la&nbsp;UDI Puntada a puntada (Costura). Esta unidad did\u00e1ctica va ayudara a nuestros alumnos y alumnas a aprender labores como coser o tejer, que tienen un gran valor pedag\u00f3gico desde la etapa de educaci\u00f3n infantil.&#46;&#46;&#46;<\/p>\n","protected":false},"author":6090,"featured_media":0,"parent":58,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/child-menu.php","meta":{"ngg_post_thumbnail":0,"footnotes":""},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/pages\/329"}],"collection":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/users\/6090"}],"replies":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/comments?post=329"}],"version-history":[{"count":3,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/pages\/329\/revisions"}],"predecessor-version":[{"id":360,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/pages\/329\/revisions\/360"}],"up":[{"embeddable":true,"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/pages\/58"}],"wp:attachment":[{"href":"https:\/\/blogsaverroes.juntadeandalucia.es\/maestramaricarmen\/wp-json\/wp\/v2\/media?parent=329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}